{"id":7306,"date":"2024-04-19T13:40:19","date_gmt":"2024-04-19T12:40:19","guid":{"rendered":"https:\/\/esg2go.org\/pagina-de-inicio-de-esg2go\/"},"modified":"2026-03-26T11:06:06","modified_gmt":"2026-03-26T10:06:06","slug":"pagina-de-inicio-de-esg2go","status":"publish","type":"page","link":"https:\/\/esg2go.org\/es\/","title":{"rendered":"P\u00e1gina de inicio de esg2go"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbHero\u00bb _builder_version=\u00bb4.25.1&#8243; background_color=\u00bbRGBA(255,255,255,0)\u00bb background_image=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2024\/04\/hero-radfahrer-sw-4-1.jpg\u00bb background_blend=\u00bbdifference\u00bb custom_padding=\u00bb0px|0px|0px|0px\u00bb animation_style=\u00bbzoom\u00bb animation_intensity_zoom=\u00bb4%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_5,3_5&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; make_equal=\u00bbon\u00bb module_class=\u00bb et_pb_row_fullwidth\u00bb _builder_version=\u00bb4.25.1&#8243; background_color=\u00bbRGBA(255,255,255,0)\u00bb background_enable_image=\u00bboff\u00bb width=\u00bb100%\u00bb width_tablet=\u00bb100%\u00bb width_phone=\u00bb100%\u00bb width_last_edited=\u00bbon|desktop\u00bb max_width=\u00bb100%\u00bb max_width_tablet=\u00bb100%\u00bb max_width_phone=\u00bb100%\u00bb max_width_last_edited=\u00bbon|desktop\u00bb custom_padding=\u00bb0px||0px|\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbtop\u00bb animation_intensity_slide=\u00bb3%\u00bb make_fullwidth=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_5&#8243; admin_label=\u00bbColumna izquierda\u00bb _builder_version=\u00bb4.25.1&#8243; background_color=\u00bb#5869BD\u00bb transform_scale_tablet=\u00bb\u00bb transform_scale_phone=\u00bb\u00bb transform_scale_last_edited=\u00bbon|desktop\u00bb transform_translate_tablet=\u00bb\u00bb transform_translate_phone=\u00bb\u00bb transform_translate_last_edited=\u00bbon|desktop\u00bb transform_rotate_tablet=\u00bb\u00bb transform_rotate_phone=\u00bb\u00bb transform_rotate_last_edited=\u00bbon|desktop\u00bb transform_skew=\u00bb175deg|175deg\u00bb transform_skew_tablet=\u00bb0deg|0deg\u00bb transform_skew_phone=\u00bb0deg|0deg\u00bb transform_skew_last_edited=\u00bbon|phone\u00bb transform_skew_linked_phone=\u00bboff\u00bb transform_origin_tablet=\u00bb\u00bb transform_origin_phone=\u00bb\u00bb transform_origin_last_edited=\u00bbon|desktop\u00bb transform_styles_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb10%|8%|10%|8%\u00bb transform_styles_tablet=\u00bb\u00bb transform_styles_phone=\u00bb\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font=\u00bb||||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_line_height=\u00bb1.2em\u00bb header_font=\u00bbHeebo|700||on|||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_font_size=\u00bb52px\u00bb header_line_height=\u00bb1.2em\u00bb background_layout=\u00bbdark\u00bb custom_margin=\u00bb||10px||false|false\u00bb animation_style=\u00bbfade\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb36px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1><strong>LA PRUEBA DE SOSTENIBILIDAD QUE NECESITAN LAS PYMES.<\/strong><\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font=\u00bbOpen Sans||||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.4em\u00bb header_font=\u00bb||||||||\u00bb custom_margin=\u00bb||50px|\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbtop\u00bb animation_intensity_slide=\u00bb17%\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb text_line_height_tablet=\u00bb1.4em\u00bb text_line_height_phone=\u00bb1.6em\u00bb text_line_height_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Cada vez se exige m\u00e1s a las empresas que informen sobre su sostenibilidad. Afortunadamente, esg2go es una soluci\u00f3n que permite a las PYME obtener una calificaci\u00f3n y los distintos informes requeridos de forma r\u00e1pida y sencilla. <\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/order.esg2go.org\/?lang=en\u00bb button_text=\u00bbHaz tu pedido ya\u00bb button_alignment=\u00bbleft\u00bb admin_label=\u00bbRegistrieren Button\u00bb _builder_version=\u00bb4.25.1&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#1D1D1B\u00bb button_bg_color=\u00bb#FFFFFF\u00bb button_border_width=\u00bb2px\u00bb button_border_color=\u00bb#1D1D1B\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bbHeebo|700||on|||||\u00bb button_icon=\u00bb&#xf054;||fa||900&#8243; button_icon_color=\u00bb#B3589D\u00bb animation_style=\u00bbfade\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_color=\u00bb#88D0EA\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_border_color_hover=\u00bb#ffffff\u00bb button_letter_spacing_hover=\u00bb2px\u00bb button_bg_color_hover=\u00bbrgba(0,0,0,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#1D1D1B\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bbon\u00bb button_border_color__hover=\u00bb#1D1D1B\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bbon\u00bb button_letter_spacing__hover=\u00bb2px\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#FFFFFF\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/esg2go.net\/?lang=es\u00bb button_text=\u00bbIntroducir datos\u00bb button_alignment=\u00bbleft\u00bb admin_label=\u00bbRegistrieren Button\u00bb _builder_version=\u00bb4.27.2&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#757575&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_border_width=\u00bb2px\u00bb button_border_color=\u00bb#757575&#8243; button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bbHeebo|700||on|||||\u00bb button_icon=\u00bb&#xf054;||fa||900&#8243; button_icon_color=\u00bb#95785E\u00bb custom_margin=\u00bb22px||||false|false\u00bb animation_style=\u00bbfade\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_color=\u00bb#88D0EA\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_border_color_hover=\u00bb#ffffff\u00bb button_letter_spacing_hover=\u00bb2px\u00bb button_bg_color_hover=\u00bbrgba(0,0,0,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#8F5A2A\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bbon\u00bb button_border_color__hover=\u00bb#8F5A2A\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bbon\u00bb button_letter_spacing__hover=\u00bb2px\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#FFFFFF\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; admin_label=\u00bbColumna derecha\u00bb _builder_version=\u00bb4.23&#8243; background_enable_image=\u00bboff\u00bb parallax=\u00bbon\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFeatures\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding=\u00bb32px|||||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb0px||||false|false\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_delay=\u00bb100ms\u00bb animation_intensity_slide=\u00bb12%\u00bb animation_starting_opacity=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbOpen Sans||||||||\u00bb text_text_color=\u00bb#1D1D1B\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.8em\u00bb custom_padding=\u00bb2vw|0px|2vw|0px|true|true\u00bb custom_padding_tablet=\u00bb|3vw||3vw|true|true\u00bb custom_padding_phone=\u00bb|10vw||10vw|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>Todav\u00eda no es tan f\u00e1cil como pedir un caf\u00e9 para llevar para demostrar lo sostenible que eres. Pero casi. Y estamos trabajando para ahorrar a\u00fan m\u00e1s tiempo a las empresas.  <\/span><span><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.25.1&#8243; animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_delay=\u00bb100ms\u00bb animation_intensity_slide=\u00bb12%\u00bb animation_starting_opacity=\u00bb80%\u00bb animation_speed_curve=\u00bbease-out\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.8em\u00bb header_font_size=\u00bb48px\u00bb header_2_font=\u00bbHeebo|900|||||||\u00bb header_2_text_color=\u00bb#5869BD\u00bb header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.3em\u00bb custom_padding_tablet=\u00bb|||0px|false|false\u00bb custom_padding_last_edited=\u00bboff|desktop\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb32px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>\u00bfQu\u00e9 significa ESG?<br \/>\u00bfY por qu\u00e9 2go?<\/h2>\n<p>Las tres primeras letras significan \u00abMedioambiental, Social, Gobernanza\u00bb. Son las tres \u00e1reas clave seg\u00fan las cuales se eval\u00faa el rendimiento de una empresa en materia de sostenibilidad. <\/p>\n<p>2go significa que puedes obtener de nosotros la prueba de sostenibilidad deseada con un esfuerzo razonable y sin largas esperas. Puede que tardes un poco m\u00e1s que si pides un caf\u00e9 para llevar. Pero trabajamos constantemente para ahorrarte tiempo.  <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb||3px|||\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_delay=\u00bb100ms\u00bb animation_intensity_slide=\u00bb12%\u00bb animation_starting_opacity=\u00bb80%\u00bb animation_speed_curve=\u00bbease-out\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.8em\u00bb header_font_size=\u00bb48px\u00bb header_2_font=\u00bbHeebo|900|||||||\u00bb header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.3em\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb32px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Tus ventajas:<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.25.1&#8243; custom_margin=\u00bb0px||||false|false\u00bb custom_padding=\u00bb||0px|||\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_delay=\u00bb100ms\u00bb animation_intensity_slide=\u00bb12%\u00bb animation_starting_opacity=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; admin_label=\u00bbLight+\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#f4f4f5&#8243; custom_padding=\u00bb30px|30px|30px|30px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbesg2go es fiable\u00bb image=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2022\/01\/pr-firm-icon-3-dark.png\u00bb icon_alignment=\u00bbleft\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.25.1&#8243; header_level=\u00bbh3&#8243; header_font=\u00bbHeebo|900|||||||\u00bb header_text_color=\u00bb#5869BD\u00bb header_font_size=\u00bb24px\u00bb header_line_height=\u00bb1.8em\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb header_font_size_tablet=\u00bb24px\u00bb header_font_size_phone=\u00bb24px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb18px\u00bb body_font_size_phone=\u00bb18px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Como pyme, recibes una pr\u00e1ctica herramienta con la que puedes medir con precisi\u00f3n tu sostenibilidad y compararte seg\u00fan el sector y el tama\u00f1o de la empresa.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; admin_label=\u00bbProfesional\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#f4f4f5&#8243; custom_padding=\u00bb30px|30px|30px|30px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbesg2go es razonable\u00bb image=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2022\/01\/pr-firm-icon-6-dark.png\u00bb icon_alignment=\u00bbleft\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.25.1&#8243; header_level=\u00bbh3&#8243; header_font=\u00bbHeebo|900|||||||\u00bb header_text_color=\u00bb#5869BD\u00bb header_font_size=\u00bb24px\u00bb header_line_height=\u00bb1.8em\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb header_font_size_tablet=\u00bb24px\u00bb header_font_size_phone=\u00bb24px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb18px\u00bb body_font_size_phone=\u00bb18px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]Almacenas tus datos b\u00e1sicos una sola vez con un esfuerzo razonable y obtienes acceso a un sistema de clasificaciones e informes. Luego puedes utilizarlos para cualquier prueba de sostenibilidad. O en marketing y comunicaci\u00f3n.[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; admin_label=\u00bbLight\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bb#f4f4f5&#8243; custom_padding=\u00bb30px|30px|30px|30px|true|true\u00bb custom_padding_tablet=\u00bb30px|30px|30px|30px|true|true\u00bb custom_padding_phone=\u00bb20px|20px|20px|20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbesg2go es seguro\u00bb image=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2022\/01\/pr-firm-icon-1-dark.png\u00bb icon_alignment=\u00bbleft\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.25.1&#8243; header_level=\u00bbh3&#8243; header_font=\u00bbHeebo|900|||||||\u00bb header_text_color=\u00bb#5869BD\u00bb header_font_size=\u00bb24px\u00bb header_line_height=\u00bb1.8em\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb header_font_size_tablet=\u00bb24px\u00bb header_font_size_phone=\u00bb24px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb18px\u00bb body_font_size_phone=\u00bb18px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Con esg2go, puedes estar seguro de que cumples en todo momento los requisitos que cambian constantemente. Por tanto, nuestra soluci\u00f3n tambi\u00e9n es econ\u00f3micamente sostenible para tu empresa. <\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_delay=\u00bb100ms\u00bb animation_intensity_slide=\u00bb12%\u00bb animation_starting_opacity=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.8em\u00bb header_font_size=\u00bb48px\u00bb header_2_font=\u00bbHeebo|900|||||||\u00bb header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.3em\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb32px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>esg2go explicado en menos de cinco minutos:<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#5869BD\u00bb width=\u00bbauto\u00bb custom_padding=\u00bb0px|0px|0px|0px|true|true\u00bb border_color_all=\u00bb#5869BD\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb background_enable_color=\u00bboff\u00bb custom_padding=\u00bb|0px||0px|false|true\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_video src=\u00bbhttps:\/\/youtu.be\/Oh2Xm1XkYaw\u00bb image_src=\u00bb\/\/i.ytimg.com\/vi\/Oh2Xm1XkYaw\/hqdefault.jpg\u00bb play_icon_color=\u00bb#FFFFFF\u00bb font_icon=\u00bb\uf04b||fa||900&#8243; thumbnail_overlay_color=\u00bbrgba(0,0,0,0.6)\u00bb _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbHeebo|900|||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb22px\u00bb custom_padding=\u00bb111px|27px|111px|27px|true|true\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Descubre de boca del propio Director, el Prof. Dr. Philipp Aerni, cu\u00e1les son las ventajas de esg2go.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb39px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/order.esg2go.org\/lang=en\u00bb button_text=\u00bbPEDIR AHORA\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#95785E\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#1D1D1B\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbHeebo|700|||||||\u00bb button_icon=\u00bb&#xf054;||fa||900&#8243; button_icon_color=\u00bb#FFFFFF\u00bb button_on_hover=\u00bboff\u00bb custom_padding=\u00bb10px|34px|10px|34px|true|true\u00bb custom_padding_tablet=\u00bb12px|28px|12px|28px|true|true\u00bb custom_padding_phone=\u00bb12px|22px|12px|22px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb button_text_size_tablet=\u00bb16px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bbon|desktop\u00bb button_letter_spacing_tablet=\u00bb2px\u00bb button_letter_spacing_phone=\u00bb1px\u00bb button_letter_spacing_last_edited=\u00bbon|desktop\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_color=\u00bb#1D1D1B\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff|hover\u00bb button_letter_spacing__hover_enabled=\u00bbon|hover\u00bb button_letter_spacing__hover=\u00bb2px\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbVideo\u00bb _builder_version=\u00bb4.25.1&#8243; animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_delay=\u00bb100ms\u00bb animation_intensity_slide=\u00bb12%\u00bb animation_starting_opacity=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row make_equal=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.8em\u00bb header_font_size=\u00bb48px\u00bb header_2_font=\u00bbHeebo|900|||||||\u00bb header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.3em\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb32px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Puedes afiliarte a partir de 300 CHF al a\u00f1o.<\/h2>\n<p>Nuestra oferta est\u00e1 adaptada a las PYME. Y nuestros precios tambi\u00e9n. La soluci\u00f3n b\u00e1sica Light cuesta 300 CHF y nuestros patrocinadores ofrecen descuentos.   <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb1px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/esg2go.org\/es\/oferta-y-precios\/\u00bb button_text=\u00bbVER OFERTA\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#95785E\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#1D1D1B\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbHeebo|700|||||||\u00bb button_icon=\u00bb&#xf054;||fa||900&#8243; button_icon_color=\u00bb#FFFFFF\u00bb button_on_hover=\u00bboff\u00bb custom_padding=\u00bb10px|34px|10px|34px|true|true\u00bb custom_padding_tablet=\u00bb12px|28px|12px|28px|true|true\u00bb custom_padding_phone=\u00bb12px|22px|12px|22px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb button_text_size_tablet=\u00bb16px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bbon|desktop\u00bb button_letter_spacing_tablet=\u00bb2px\u00bb button_letter_spacing_phone=\u00bb1px\u00bb button_letter_spacing_last_edited=\u00bbon|desktop\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_color=\u00bb#1D1D1B\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff|hover\u00bb button_letter_spacing__hover_enabled=\u00bbon|hover\u00bb button_letter_spacing__hover=\u00bb2px\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row make_equal=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.8em\u00bb header_font_size=\u00bb48px\u00bb header_2_font=\u00bbHeebo|900|||||||\u00bb header_2_font_size=\u00bb48px\u00bb header_2_letter_spacing=\u00bb1px\u00bb header_2_line_height=\u00bb1.3em\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb32px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Hablando de esfuerzo: en el primer a\u00f1o, debes esperar pasar alrededor de un d\u00eda laborable investigando todas las cifras clave que necesitas. Despu\u00e9s, estar\u00e1s en marcha en un abrir y cerrar de ojos. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbVideo\u00bb _builder_version=\u00bb4.25.1&#8243; animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_delay=\u00bb100ms\u00bb animation_intensity_slide=\u00bb12%\u00bb animation_starting_opacity=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb3_4,1_4&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.8em\u00bb header_font_size=\u00bb48px\u00bb header_2_font=\u00bbHeebo|900|||||||\u00bb header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.3em\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb32px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><span style=\"background-position: 0% 0%; background-repeat: repeat; background-attachment: scroll; background-image: none; background-size: auto; background-origin: padding-box; background-clip: border-box;\"><\/span> <span lang=\"EN-GB\" style=\"background-position: 0% 0%; background-repeat: repeat; background-attachment: scroll; background-image: none; background-size: auto; background-origin: padding-box; background-clip: border-box;\">Norma GRI<\/span><\/h2>\n<p>Adem\u00e1s de nuestra propia clasificaci\u00f3n, tambi\u00e9n ofrecemos plantillas que cumplen las normas establecidas para la elaboraci\u00f3n de informes y estamos reconocidos por la GRI como \u00abSocio de Software y Herramientas de la GRI\u00bb.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2025\/09\/GRI-LicensingMarks-Partner2025-v1.png\u00bb alt=\u00bbLogotipo GRI Software y Herramientas Socio 2025&#8243; title_text=\u00bbGRI-LicensingMarks-Socio2025-v1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbs_accordion_lila\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_delay=\u00bb100ms\u00bb animation_intensity_slide=\u00bb12%\u00bb animation_starting_opacity=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row make_equal=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb1.8em\u00bb header_2_font=\u00bbHeebo|900|||||||\u00bb header_2_font_size=\u00bb48px\u00bb header_2_letter_spacing=\u00bb1px\u00bb header_2_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb||||false|false\u00bb custom_padding_tablet=\u00bb|||0px|false|false\u00bb custom_padding_last_edited=\u00bboff|desktop\u00bb text_font_size_tablet=\u00bb18px\u00bb text_font_size_phone=\u00bb16px\u00bb text_font_size_last_edited=\u00bbon|desktop\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb32px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Es bueno saberlo:<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion open_toggle_text_color=\u00bb#5869BD\u00bb closed_toggle_text_color=\u00bb#1D1D1B\u00bb closed_toggle_background_color=\u00bb#FFFFFF\u00bb toggle_icon=\u00bb&#x3d;||divi||400&#8243; icon_color=\u00bb#8F5A2A\u00bb use_icon_font_size=\u00bbon\u00bb icon_font_size=\u00bb24px\u00bb admin_label=\u00bbs_accordion_lila_inhalt\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb toggle_text_color=\u00bb#5869BD\u00bb toggle_level=\u00bbh2&#8243; toggle_font=\u00bbHeebo|600|||||||\u00bb toggle_font_size=\u00bb28px\u00bb closed_toggle_font=\u00bbHeebo|600|||||||\u00bb body_font_size=\u00bb22px\u00bb body_line_height=\u00bb1.8em\u00bb background_color=\u00bb#FFFFFF\u00bb toggle_font_size_tablet=\u00bb26px\u00bb toggle_font_size_phone=\u00bb26px\u00bb toggle_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb20px\u00bb body_font_size_phone=\u00bb18px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb border_width_all=\u00bb0px\u00bb border_color_top=\u00bb#5869BD\u00bb border_width_bottom=\u00bb2px\u00bb border_color_bottom=\u00bb#969696&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_accordion_item title=\u00bbAmpliamente aceptado por Zurich, UBS, Swiss Post, SBB y Allianz.\u00bb open=\u00bbon\u00bb open_toggle_text_color=\u00bb#1D1D1B\u00bb closed_toggle_text_color=\u00bb#1D1D1B\u00bb icon_color=\u00bb#1D1D1B\u00bb toggle_icon=\u00bb&#xf054;||fa||900&#8243; open_icon_color=\u00bb#1D1D1B\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Con m\u00e1s de 1.000 licencias canjeadas, esg2go es la herramienta suiza de calificaci\u00f3n ESG con un alto nivel de aceptaci\u00f3n. Nuestro Sistema de Calificaci\u00f3n e Informes cuenta con el apoyo de patrocinadores de renombre y el respaldo activo de asociaciones. esg2go es ahora una norma ampliamente reconocida en Suiza.<\/p>\n<ul>\n<li><a href=\"https:\/\/esg2go.org\/es\/comunidad\/\">Comunidad esg2go<\/a>: Actualmente, m\u00e1s de 300 clientes de esg2go que han completado una valoraci\u00f3n completa han accedido a proporcionar informaci\u00f3n sobre sus experiencias con esg2go.<\/li>\n<li><a href=\"https:\/\/esg2go.org\/es\/profesionales-y-socios\/\">Profesionales de<\/a> esg2go: esg2go cuenta con una red nacional de m\u00e1s de 50 consultores independientes que ayudan con las aportaciones y la interpretaci\u00f3n de la valoraci\u00f3n de esg2go.<\/li>\n<li><a href=\"https:\/\/www.post.ch\/-\/media\/post\/beschaffung\/dokumente\/news-beschaffung\/2024\/31-01-2024-news-beschaffung-konzern.pdf\" target=\"_blank\" rel=\"noopener\">Swiss Post<\/a>: Desde principios de 2024, se valora la calificaci\u00f3n de esg2go como prueba de sostenibilidad en las ofertas. Swiss Post exige a sus proveedores estrat\u00e9gicos y a los proveedores con mayores riesgos que sean calificados por la <a href=\"https:\/\/www1.post.ch\/-\/media\/post\/beschaffung\/dokumente\/news-beschaffung\/2024\/27-09-2024-newsletter-beschaffung.pdf\" target=\"_blank\" rel=\"noopener\">plataforma de calificaci\u00f3n<\/a> definida por Swiss Post.<\/li>\n<li>Desde oto\u00f1o de 2024, <a href=\"https:\/\/company.sbb.ch\/de\/sbb-als-geschaeftspartner\/einkauf\/nachhaltige-beschaffung.html\" target=\"_blank\" rel=\"noopener\">SBB<\/a> y <a href=\"https:\/\/www.allianz.ch\/de\/ueber-uns\/sustainability.html\" target=\"_blank\" rel=\"noopener\">Allianz Suisse Insurance Company<\/a> est\u00e1n empatados con Swiss Post.<\/li>\n<li><a href=\"https:\/\/www.hotelleriesuisse.ch\/de\/leistungen-und-support\/marketing-und-distribution\/esg2go-pilotprojekt\" target=\"_blank\" rel=\"noopener\">HotellerieSuisse<\/a>: Junto con muchas otras asociaciones, HotellerieSuisse apoya el uso de esg2go e integra la herramienta en su seguimiento de la asociaci\u00f3n.<\/li>\n<li><a href=\"https:\/\/www.kmu.admin.ch\/kmu\/de\/home\/fakten-trends\/corporate-social-responsibility-csr\/nachhaltigkeit-messen.html\" target=\"_blank\" rel=\"noopener\">Portal PYME<\/a> de Seco: Como ejemplo de los muchos otros portales, sitios de medios de comunicaci\u00f3n y sitios web de clientes, nos gustar\u00eda mencionar la atractiva descripci\u00f3n de Seco, que anima a la participaci\u00f3n.<\/li>\n<\/ul>\n<p>Puedes conocer todos los detalles en nuestro <a href=\"https:\/\/adjumed.com\/download\/esg2go\/presse\/pres2411\/whit2410white_paper_zur_hohen_akzeptanz_von_esg2go.pdf\" target=\"_blank\" rel=\"noopener\" title=\"Libro Blanco sobre la aceptaci\u00f3n de las herramientas ESG\">libro blanco sobre la aceptaci\u00f3n de las herramientas ESG<\/a>.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbPreparado para la informaci\u00f3n internacional\u00bb open_toggle_text_color=\u00bb#1D1D1B\u00bb closed_toggle_text_color=\u00bb#1D1D1B\u00bb icon_color=\u00bb#1D1D1B\u00bb toggle_icon=\u00bb&#xf054;||fa||900&#8243; open_icon_color=\u00bb#1D1D1B\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||||false|false\u00bb custom_css_free_form=\u00bbwidth: 50%;||display: inline-block;||vertical-align: top;||padding: 10px;\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p>Ofrecemos plantillas de informes compatibles con CSRD VSME y GRI,<br \/>que pueden rellenarse con tus datos en un proceso semiautomatizado.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbVivimos la apertura.\u00bb open_toggle_text_color=\u00bb#1D1D1B\u00bb closed_toggle_text_color=\u00bb#1D1D1B\u00bb icon_color=\u00bb#1D1D1B\u00bb toggle_icon=\u00bb&#xf054;||fa||900&#8243; open_icon_color=\u00bb#1D1D1B\u00bb _builder_version=\u00bb4.27.3&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p>Nuestras valoraciones son transparentes, nuestro equipo agradece el di\u00e1logo y nuestras interfaces est\u00e1n a disposici\u00f3n de terceros. Estamos convencidos de que el pensamiento de jardiner\u00eda no hace que el mundo sea m\u00e1s sostenible. <\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbN\u00fameros en lugar de greenwashing.\u00bb open_toggle_text_color=\u00bb#1D1D1B\u00bb closed_toggle_text_color=\u00bb#1D1D1B\u00bb icon_color=\u00bb#1D1D1B\u00bb toggle_icon=\u00bb&#xf054;||fa||900&#8243; open_icon_color=\u00bb#1D1D1B\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p>Las im\u00e1genes bonitas y las palabras turbias no son sostenibles. Los hechos lo son. esg2go es sin\u00f3nimo de comparaciones precisas y evaluaciones comparativas diferenciadas, claras y comprensibles.  <\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbSin conflictos de intereses.\u00bb open_toggle_text_color=\u00bb#1D1D1B\u00bb closed_toggle_text_color=\u00bb#1D1D1B\u00bb icon_color=\u00bb#1D1D1B\u00bb toggle_icon=\u00bb&#xf054;||fa||900&#8243; open_icon_color=\u00bb#1D1D1B\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||||false|false\u00bb custom_css_before=\u00bb  -moz-hyphens: auto;||  -o-hyphens: auto;||  -webkit-hyphens: auto;||  -ms-hyphens: auto;||  hyphens: auto; \u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p>Nosotros gestionamos la plataforma y creamos las calificaciones y los informes. Todo el asesoramiento corre a cargo de <a href=\"https:\/\/esg2go.org\/es\/profesionales-y-socios\/\">profesionales<\/a> independientes, mientras que la verificaci\u00f3n la realizan auditores independientes acreditados, como <a href=\"https:\/\/www.sqs.ch\/de\/dienstleistungen\/produkte\/esg2go\" target=\"_blank\" rel=\"noopener\" title=\"https:\/\/www.sqs.ch\/de\/dienstleistungen\/produkte\/esg2go\">SQS<\/a> (nuestro \u00abSocio de Verificaci\u00f3n Preferente\u00bb). De este modo, garantizamos que el resultado sea objetivo y justo.  <\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbEspecialmente para las pymes.\u00bb open_toggle_text_color=\u00bb#1D1D1B\u00bb closed_toggle_text_color=\u00bb#1D1D1B\u00bb icon_color=\u00bb#1D1D1B\u00bb toggle_icon=\u00bb&#xf054;||fa||900&#8243; open_icon_color=\u00bb#1D1D1B\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p>Existen muchas calificaciones ESG. Sin embargo, se centran en las empresas que cotizan en bolsa. Si eres una PYME y no quieres contratar un departamento de cumplimiento y un Consejo Asesor de Sostenibilidad de 10 miembros, somos el socio adecuado para ti.  <\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFeatures\u00bb _builder_version=\u00bb4.25.1&#8243; animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_delay=\u00bb100ms\u00bb animation_intensity_slide=\u00bb12%\u00bb animation_starting_opacity=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.6&#8243; custom_padding=\u00bb||0px|||\u00bb hover_enabled=\u00bb0&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243; custom_margin=\u00bb||0px||false|false\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.8em\u00bb header_font_size=\u00bb48px\u00bb header_2_font=\u00bbHeebo|900|||||||\u00bb header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.3em\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb32px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb custom_margin=\u00bb||1px|||\u00bb]<\/p>\n<h2>\u00bfQui\u00e9n est\u00e1 detr\u00e1s?<\/h2>\n<p>esg2go es una asociaci\u00f3n p\u00fablico-privada entre el CCRS | Stiftung Zentrum Nachhaltigkeit y el proveedor de tecnolog\u00eda Adjumed Services AG.<\/p>\n<p>[\/et_pb_text][et_pb_blurb icon_placement=\u00bbleft\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh3&#8243; header_font=\u00bbHeebo|900|||||||\u00bb header_font_size=\u00bb18px\u00bb header_line_height=\u00bb2em\u00bb body_text_color=\u00bb#1D1D1B\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb2em\u00bb custom_margin=\u00bb0px|||-8px|false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_padding=\u00bb1px||1vw||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2026\/03\/ccrs-2025-320-241.jpg\u00bb alt=\u00bbCCRS\u00bb title_text=\u00bbLogo CCRS | Stiftung Zentrum Nachhaltigkeit\u00bb url=\u00bbhttps:\/\/www.ccrs.ch\u00bb url_new_window=\u00bbon\u00bb align=\u00bbcenter\u00bb module_class=\u00bbgrayscale\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|11px|||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2022\/01\/adjumed-341.jpg\u00bb alt=\u00bbLogotipo Adjumed Services AG\u00bb title_text=\u00bbadjunto-341&#8243; url=\u00bbhttps:\/\/adjumed.com\u00bb url_new_window=\u00bbon\u00bb align=\u00bbcenter\u00bb module_class=\u00bbgrayscale\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|11px|||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; make_equal=\u00bbon\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_padding=\u00bb1px||1vw||false|false\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2022\/01\/ccrs-341.jpg\u00bb alt=\u00bbLogotipo CCRS\u00bb title_text=\u00bbccrs-341&#8243; url=\u00bbhttps:\/\/www.ccrs.ch\u00bb url_new_window=\u00bbon\u00bb module_class=\u00bbgrayscale\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|11px|||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2022\/01\/hfw-fribourg-2.jpg\u00bb alt=\u00bbLogotipo HfW Fribourg\u00bb title_text=\u00bbLogotipo HfW Fribourg\u00bb url=\u00bbhttps:\/\/www.ccrs.ch\u00bb url_new_window=\u00bbon\u00bb module_class=\u00bbgrayscale\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|11px|||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2022\/01\/adjumed-341.jpg\u00bb alt=\u00bbLogotipo Adjumed Services AG\u00bb title_text=\u00bbadjunto-341&#8243; url=\u00bbhttps:\/\/adjumed.com\u00bb url_new_window=\u00bbon\u00bb module_class=\u00bbgrayscale\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|11px|||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb2px||48px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/esg2go.org\/es\/equipo-e-historia\/\u00bb button_text=\u00bbM\u00c1S SOBRE NOSOTROS\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#95785E\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#1D1D1B\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbHeebo|700|||||||\u00bb button_icon=\u00bb&#xf054;||fa||900&#8243; button_icon_color=\u00bb#FFFFFF\u00bb button_on_hover=\u00bboff\u00bb custom_padding=\u00bb10px|34px|10px|34px|true|true\u00bb custom_padding_tablet=\u00bb12px|28px|12px|28px|true|true\u00bb custom_padding_phone=\u00bb12px|22px|12px|22px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb button_text_size_tablet=\u00bb16px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bbon|desktop\u00bb button_letter_spacing_tablet=\u00bb2px\u00bb button_letter_spacing_phone=\u00bb1px\u00bb button_letter_spacing_last_edited=\u00bbon|desktop\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_color=\u00bb#1D1D1B\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff|hover\u00bb button_letter_spacing__hover_enabled=\u00bbon|hover\u00bb button_letter_spacing__hover=\u00bb2px\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb||2px|||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.8em\u00bb header_2_font=\u00bbHeebo|900|||||||\u00bb header_2_font_size=\u00bb66px\u00bb header_2_line_height=\u00bb1.3em\u00bb custom_margin=\u00bb||1px|||\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb58px\u00bb header_2_font_size_phone=\u00bb40px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Contamos con el apoyo de los siguientes socios estrat\u00e9gicos:<\/p>\n<p>[\/et_pb_text][et_pb_blurb icon_placement=\u00bbleft\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh3&#8243; header_font=\u00bbHeebo|900|||||||\u00bb header_font_size=\u00bb18px\u00bb header_line_height=\u00bb2em\u00bb body_text_color=\u00bb#1D1D1B\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb2em\u00bb custom_margin=\u00bb0px|||-8px|false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_padding=\u00bb||2vw||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2022\/01\/ubs-320.jpg\u00bb alt=\u00bbLogotipo CCRS\u00bb title_text=\u00bbubs-320&#8243; url=\u00bbhttps:\/\/www.ubs.com\/ch\/de\/microsites\/sustainability.html\u00bb url_new_window=\u00bbon\u00bb align=\u00bbcenter\u00bb module_class=\u00bbgrayscale\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|11px|||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2022\/01\/zurich-320-2.jpg\u00bb alt=\u00bbLogotipo Adjumed Services AG\u00bb title_text=\u00bbzurich-320-2&#8243; url=\u00bbhttps:\/\/www.zurich.ch\/de\/ueber-uns\/corporate-responsibility\/corporate-responsibility\u00bb url_new_window=\u00bbon\u00bb align=\u00bbcenter\u00bb module_class=\u00bbgrayscale\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|11px|||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_padding=\u00bb0px||2vw||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2022\/01\/swiss-cleanteach-320.jpg\u00bb alt=\u00bbLogotipo CCRS\u00bb title_text=\u00bbswiss-cleananteach-320&#8243; url=\u00bbhttps:\/\/www.swisscleantech.ch\u00bb url_new_window=\u00bbon\u00bb module_class=\u00bbgrayscale\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|11px|||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2022\/10\/Renaissance_Logo_320_D.jpg\u00bb alt=\u00bbLogotipo de la Fundaci\u00f3n Renacimiento\u00bb title_text=\u00bbRenaissance_Logo_320_D\u00bb url=\u00bbhttps:\/\/renaissance.net\/de\/\u00bb url_new_window=\u00bbon\u00bb module_class=\u00bbgrayscale\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|11px|||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2023\/01\/raiffeisen_logo-1.png\u00bb alt=\u00bbRaiffeisen\u00bb title_text=\u00bbRaiffeisen\u00bb url=\u00bbhttps:\/\/www.raiffeisen.ch\/zuerich\/de\/ueber-uns\/nachhaltigkeit.html\u00bb url_new_window=\u00bbon\u00bb module_class=\u00bbgrayscale\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|11px|||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/esg2go.org\/wp-content\/uploads\/2023\/02\/sqs_logo2.png\u00bb alt=\u00bbRaiffeisen\u00bb title_text=\u00bbsqs_logo2&#8243; url=\u00bbhttps:\/\/www.sqs.ch\/de\/dienstleistungen\/produkte\/esg2go\u00bb url_new_window=\u00bbon\u00bb module_class=\u00bbgrayscale\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|11px|||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb||2px|||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.0&#8243; text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.8em\u00bb header_font_size=\u00bb48px\u00bb header_2_font=\u00bbHeebo|900|||||||\u00bb header_2_font_size=\u00bb48px\u00bb header_2_letter_spacing=\u00bb1px\u00bb header_2_line_height=\u00bb1.3em\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb32px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Tambi\u00e9n trabajamos con unos 50 profesionales y muchos socios que estar\u00e1n encantados de ayudarte.<\/p>\n<p>[\/et_pb_text][et_pb_blurb icon_placement=\u00bbleft\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh3&#8243; header_font=\u00bbHeebo|900|||||||\u00bb header_font_size=\u00bb18px\u00bb header_line_height=\u00bb2em\u00bb body_text_color=\u00bb#1D1D1B\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb2em\u00bb custom_margin=\u00bb0px|||-8px|false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb39px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/esg2go.org\/es\/profesionales-y-socios\/\u00bb button_text=\u00bbA LOS PROFESIONALES Y SOCIOS\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#95785E\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#1D1D1B\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbHeebo|700|||||||\u00bb button_icon=\u00bb&#xf054;||fa||900&#8243; button_icon_color=\u00bb#FFFFFF\u00bb button_on_hover=\u00bboff\u00bb custom_padding=\u00bb10px|34px|10px|34px|true|true\u00bb custom_padding_tablet=\u00bb12px|28px|12px|28px|true|true\u00bb custom_padding_phone=\u00bb12px|22px|12px|22px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb button_text_size_tablet=\u00bb16px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bbon|desktop\u00bb button_letter_spacing_tablet=\u00bb2px\u00bb button_letter_spacing_phone=\u00bb1px\u00bb button_letter_spacing_last_edited=\u00bbon|desktop\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_color=\u00bb#1D1D1B\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff|hover\u00bb button_letter_spacing__hover_enabled=\u00bbon|hover\u00bb button_letter_spacing__hover=\u00bb2px\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbVideo\u00bb _builder_version=\u00bb4.25.1&#8243; custom_padding=\u00bb||32px|||\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_delay=\u00bb100ms\u00bb animation_intensity_slide=\u00bb12%\u00bb animation_starting_opacity=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row make_equal=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.8em\u00bb header_font_size=\u00bb48px\u00bb header_2_font=\u00bbHeebo|900|||||||\u00bb header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.3em\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb32px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>\u00bfC\u00f3mo de f\u00e1cil es realmente esg2go?<\/h2>\n<p>Para comprobarlo, lee lo que otras pymes escriben sobre nosotros:<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbTestimonials\u00bb _builder_version=\u00bb4.25.1&#8243; background_color=\u00bb#88D0EA\u00bb background_enable_image=\u00bboff\u00bb custom_padding=\u00bb0vw||0vw||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.25.1&#8243; width=\u00bb100%\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb custom_css_free_form=\u00bbselector .et-pb-slider-arrows a.et-pb-arrow-prev,||selector .et-pb-slider-arrows a.et-pb-arrow-next {||\topacity: 1;||}||selector .et-pb-slider-arrows a.et-pb-arrow-prev {||\tleft: 22px;||}||||selector .et-pb-slider-arrows a.et-pb-arrow-next {||\tright: 22px;||}\u00bb border_color_all=\u00bb#ffffff\u00bb border_width_right_tablet=\u00bb\u00bb border_width_right_phone=\u00bb0px\u00bb border_width_right_last_edited=\u00bbon|phone\u00bb border_width_bottom_tablet=\u00bb\u00bb border_width_bottom_phone=\u00bb0px\u00bb border_width_bottom_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_slider use_bg_overlay=\u00bboff\u00bb use_text_overlay=\u00bboff\u00bb arrows_custom_color=\u00bb#88D0EA\u00bb dot_nav_custom_color=\u00bb#88D0EA\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bbHeebo|900|||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_font_size=\u00bb48px\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbHeebo|700|||||||\u00bb body_text_color=\u00bb#FFFFFF\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb background_color=\u00bbrgba(0,0,0,0)\u00bb custom_margin=\u00bb|-42px||-42px|false|true\u00bb custom_padding=\u00bb96px|0px|96px|0px|true|true\u00bb custom_padding_tablet=\u00bb48px|13%|48px|13%|true|true\u00bb custom_padding_phone=\u00bb28px|12%|28px|12%|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb auto=\u00bbon\u00bb link_option_url=\u00bbhttps:\/\/esg2go.net\u00bb header_font_size_tablet=\u00bb24px\u00bb header_font_size_phone=\u00bb18px\u00bb header_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb arrows_custom_color__hover_enabled=\u00bbon|desktop\u00bb show_arrows__hover_enabled=\u00bbon|hover\u00bb arrows_custom_color__hover=\u00bb#88D0EA\u00bb][et_pb_slide heading=\u00bb%22esg2go es un verdadero rayo de esperanza: Sencillo, claro, fiable, abierto, funcional, seguro y especialmente respetuoso con lo que hacemos como pyme por la sostenibilidad.%22&#8243; _builder_version=\u00bb4.23&#8243; header_level=\u00bbh6&#8243; header_font_size=\u00bb32px\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.4em\u00bb header_font_size_tablet=\u00bb24px\u00bb header_font_size_phone=\u00bb16px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb18px\u00bb body_font_size_phone=\u00bb12px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>Franz Wyss, Director General de Ticketino AG<\/p>\n<p>[\/et_pb_slide][et_pb_slide heading=\u00bb%22esg2go ayuda a las pymes de forma pragm\u00e1tica y eficaz a optimizar su actuaci\u00f3n en cuestiones ASG hoy, antes de que se vean obligadas a hacerlo ma\u00f1ana por normativas oficiales o requisitos del sector privado.%22&#8243; _builder_version=\u00bb4.17.4&#8243; header_level=\u00bbh6&#8243; header_font_size=\u00bb32px\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.4em\u00bb header_font_size_tablet=\u00bb24px\u00bb header_font_size_phone=\u00bb16px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb18px\u00bb body_font_size_phone=\u00bb12px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>Hannes M\u00fcller, Director General en el punto. &#8211; Estrategia creativa e innovaci\u00f3n <\/p>\n<p>[\/et_pb_slide][et_pb_slide heading=\u00bb%22Nos gusta mucho el planteamiento de esg2go y estamos convencidos de que es la forma correcta de crear una herramienta de calificaci\u00f3n eficaz. esg2go tiene potencial para convertirse en una herramienta de calificaci\u00f3n aceptada nacional e internacionalmente, que sea f\u00e1cil de utilizar para las pymes y las organizaciones y que, al mismo tiempo, represente un instrumento eficaz para una sostenibilidad medible y comparable.%22&#8243; _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh6&#8243; header_font_size=\u00bb28px\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.4em\u00bb header_font_size_tablet=\u00bb24px\u00bb header_font_size_phone=\u00bb16px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb\u00bb body_font_size_phone=\u00bb12px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>Andreas Roos, Jefe de Ventas y Marketing ADAMS Schweiz AG<\/p>\n<p>[\/et_pb_slide][\/et_pb_slider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbVideo\u00bb _builder_version=\u00bb4.25.1&#8243; animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_delay=\u00bb100ms\u00bb animation_intensity_slide=\u00bb12%\u00bb animation_starting_opacity=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row make_equal=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.8em\u00bb header_font_size=\u00bb48px\u00bb header_2_font=\u00bbHeebo|900|||||||\u00bb header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.3em\u00bb text_font_size_tablet=\u00bb20px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb32px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>\u00bfTienes alguna pregunta?<\/h2>\n<p>ESG es un tema complejo. Si necesitas informaci\u00f3n inmediata, lo mejor es que busques una respuesta en nuestras FAQ. Por supuesto, tambi\u00e9n estaremos encantados de ayudarte personalmente.  <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb39px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bb&lt;!&#8211;&#91;CDATA&#91;mailto:esg2go@esg2go.com&#93;&#93;&#8211;&gt;\u00bb button_text=\u00bbCONT\u00c1CTANOS\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#95785E\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#1D1D1B\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbHeebo|700|||||||\u00bb button_icon=\u00bb&#xf054;||fa||900&#8243; button_icon_color=\u00bb#FFFFFF\u00bb button_on_hover=\u00bboff\u00bb custom_padding=\u00bb10px|34px|10px|34px|true|true\u00bb custom_padding_tablet=\u00bb12px|28px|12px|28px|true|true\u00bb custom_padding_phone=\u00bb12px|22px|12px|22px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb button_text_size_tablet=\u00bb16px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bbon|desktop\u00bb button_letter_spacing_tablet=\u00bb2px\u00bb button_letter_spacing_phone=\u00bb1px\u00bb button_letter_spacing_last_edited=\u00bbon|desktop\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb4px\u00bb box_shadow_vertical=\u00bb4px\u00bb box_shadow_color=\u00bb#1D1D1B\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff|hover\u00bb button_letter_spacing__hover_enabled=\u00bbon|hover\u00bb button_letter_spacing__hover=\u00bb2px\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA PRUEBA DE SOSTENIBILIDAD QUE NECESITAN LAS PYMES.Cada vez se exige m\u00e1s a las empresas que informen sobre su sostenibilidad. Afortunadamente, esg2go es una soluci\u00f3n que permite a las PYME obtener una calificaci\u00f3n y los distintos informes requeridos de forma r\u00e1pida y sencilla. Todav\u00eda no es tan f\u00e1cil como pedir un caf\u00e9 para llevar para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-7306","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>esg2go | Der einfache Nachhaltigkeitsnachweis f\u00fcr KMU<\/title>\n<meta name=\"description\" content=\"Ofrecemos valoraciones e informes para las pymes suizas que quieran o necesiten demostrar su compromiso con la sostenibilidad de forma justa, transparente y abierta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esg2go.org\/es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"esg2go | Der einfache Nachhaltigkeitsnachweis f\u00fcr KMU\" \/>\n<meta property=\"og:description\" content=\"Ofrecemos valoraciones e informes para las pymes suizas que quieran o necesiten demostrar su compromiso con la sostenibilidad de forma justa, transparente y abierta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esg2go.org\/es\/\" \/>\n<meta property=\"og:site_name\" content=\"esg2go\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T10:06:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"38 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esg2go.org\\\/es\\\/\",\"url\":\"https:\\\/\\\/esg2go.org\\\/es\\\/\",\"name\":\"esg2go | Der einfache Nachhaltigkeitsnachweis f\u00fcr KMU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esg2go.org\\\/es\\\/#website\"},\"datePublished\":\"2024-04-19T12:40:19+00:00\",\"dateModified\":\"2026-03-26T10:06:06+00:00\",\"description\":\"Ofrecemos valoraciones e informes para las pymes suizas que quieran o necesiten demostrar su compromiso con la sostenibilidad de forma justa, transparente y abierta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esg2go.org\\\/es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esg2go.org\\\/es\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esg2go.org\\\/es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/esg2go.org\\\/es\\\/pagina-de-inicio-de-esg2go\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P\u00e1gina de inicio de esg2go\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esg2go.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/esg2go.org\\\/es\\\/\",\"name\":\"esg2go\",\"description\":\"Der einfache Nachhaltigkeitsnachweis f\u00fcr KMU\",\"publisher\":{\"@id\":\"https:\\\/\\\/esg2go.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esg2go.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esg2go.org\\\/es\\\/#organization\",\"name\":\"esg2go\",\"url\":\"https:\\\/\\\/esg2go.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esg2go.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esg2go.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/favicon-esg2go.png\",\"contentUrl\":\"https:\\\/\\\/esg2go.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/favicon-esg2go.png\",\"width\":512,\"height\":512,\"caption\":\"esg2go\"},\"image\":{\"@id\":\"https:\\\/\\\/esg2go.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/esg2go\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"esg2go | Der einfache Nachhaltigkeitsnachweis f\u00fcr KMU","description":"Ofrecemos valoraciones e informes para las pymes suizas que quieran o necesiten demostrar su compromiso con la sostenibilidad de forma justa, transparente y abierta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esg2go.org\/es\/","og_locale":"es_ES","og_type":"article","og_title":"esg2go | Der einfache Nachhaltigkeitsnachweis f\u00fcr KMU","og_description":"Ofrecemos valoraciones e informes para las pymes suizas que quieran o necesiten demostrar su compromiso con la sostenibilidad de forma justa, transparente y abierta.","og_url":"https:\/\/esg2go.org\/es\/","og_site_name":"esg2go","article_modified_time":"2026-03-26T10:06:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"38 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/esg2go.org\/es\/","url":"https:\/\/esg2go.org\/es\/","name":"esg2go | Der einfache Nachhaltigkeitsnachweis f\u00fcr KMU","isPartOf":{"@id":"https:\/\/esg2go.org\/es\/#website"},"datePublished":"2024-04-19T12:40:19+00:00","dateModified":"2026-03-26T10:06:06+00:00","description":"Ofrecemos valoraciones e informes para las pymes suizas que quieran o necesiten demostrar su compromiso con la sostenibilidad de forma justa, transparente y abierta.","breadcrumb":{"@id":"https:\/\/esg2go.org\/es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esg2go.org\/es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/esg2go.org\/es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/esg2go.org\/es\/pagina-de-inicio-de-esg2go\/"},{"@type":"ListItem","position":2,"name":"P\u00e1gina de inicio de esg2go"}]},{"@type":"WebSite","@id":"https:\/\/esg2go.org\/es\/#website","url":"https:\/\/esg2go.org\/es\/","name":"esg2go","description":"Der einfache Nachhaltigkeitsnachweis f\u00fcr KMU","publisher":{"@id":"https:\/\/esg2go.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esg2go.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/esg2go.org\/es\/#organization","name":"esg2go","url":"https:\/\/esg2go.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esg2go.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/esg2go.org\/wp-content\/uploads\/2024\/05\/favicon-esg2go.png","contentUrl":"https:\/\/esg2go.org\/wp-content\/uploads\/2024\/05\/favicon-esg2go.png","width":512,"height":512,"caption":"esg2go"},"image":{"@id":"https:\/\/esg2go.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/esg2go"]}]}},"_links":{"self":[{"href":"https:\/\/esg2go.org\/es\/wp-json\/wp\/v2\/pages\/7306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esg2go.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/esg2go.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/esg2go.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esg2go.org\/es\/wp-json\/wp\/v2\/comments?post=7306"}],"version-history":[{"count":53,"href":"https:\/\/esg2go.org\/es\/wp-json\/wp\/v2\/pages\/7306\/revisions"}],"predecessor-version":[{"id":25979739,"href":"https:\/\/esg2go.org\/es\/wp-json\/wp\/v2\/pages\/7306\/revisions\/25979739"}],"wp:attachment":[{"href":"https:\/\/esg2go.org\/es\/wp-json\/wp\/v2\/media?parent=7306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}